{"id":705,"date":"2024-02-13T08:55:28","date_gmt":"2024-02-13T08:55:28","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=705"},"modified":"2026-06-29T13:32:33","modified_gmt":"2026-06-29T18:32:33","slug":"mix-soul-8","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/705","title":{"rendered":"Mix Soul 8"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/encrypted-tbn0.gstatic.com\/images?q=tbn:ANd9GcRLIFiMHT1NpDirXncIdBtLZezrBytrVqFIhQ&#038;s\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abMix Soul 8\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-705-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.archive.org\/download\/AQPRadio11\/MIXSoul8.mp3?_=1\" \/><a href=\"http:\/\/www.archive.org\/download\/AQPRadio11\/MIXSoul8.mp3\">http:\/\/www.archive.org\/download\/AQPRadio11\/MIXSoul8.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Soul 8\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-705","post","type-post","status-publish","format-standard","hentry","category-musica-disco-soul"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=705"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/705\/revisions"}],"predecessor-version":[{"id":87206,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/705\/revisions\/87206"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}