{"id":7177,"date":"2023-06-26T00:14:42","date_gmt":"2023-06-26T00:14:42","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=7177"},"modified":"2026-06-29T13:43:38","modified_gmt":"2026-06-29T18:43:38","slug":"paul-nero-detroit-soul-party","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/7177","title":{"rendered":"Paul Nero &#8211; Detroit Soul Party"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/img.discogs.com\/YwUbGJr0lTb06QI33N0ugeFBgCM=\/fit-in\/600x599\/filters:strip_icc():format(jpeg):mode_rgb():quality(90)\/discogs-images\/R-6545565-1421689174-1361.jpeg.jpg\" alt=\"\" width=\"98%\" align=\"center\" \/> <\/p>\n<p>\u00abPaul Nero &#8211; Detroit Soul Party\u00bb <\/p>\n<p><strong>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-7177-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio342\/Mix_PaulNero_DetroitSoulParty.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio342\/Mix_PaulNero_DetroitSoulParty.mp3\">http:\/\/archive.org\/download\/AQPRadio342\/Mix_PaulNero_DetroitSoulParty.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abPaul Nero &#8211; Detroit Soul Party\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-7177","post","type-post","status-publish","format-standard","hentry","category-musica-disco-soul"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/7177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=7177"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/7177\/revisions"}],"predecessor-version":[{"id":87869,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/7177\/revisions\/87869"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=7177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=7177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=7177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}