{"id":7387,"date":"2023-07-10T05:22:16","date_gmt":"2023-07-10T05:22:16","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=7387"},"modified":"2026-06-29T13:41:37","modified_gmt":"2026-06-29T18:41:37","slug":"mix-relax-67-electronic","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/7387","title":{"rendered":"Mix Relax 67 &#8211; Electronic"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/s2.best-wallpaper.net\/wallpaper\/1920x1200\/1603\/Vietnam-beautiful-scenery-sea-rocks-islands-trees-leaves-boats_1920x1200.jpg\" alt=\"\" width=\"98%\" align=\"center\" \/><\/p>\n<p> \u00abMix Relax 67 &#8211; Electronic\u00bb <\/p>\n<p><strong>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-7387-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio350\/MixRelax67_electronic.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio350\/MixRelax67_electronic.mp3\">http:\/\/archive.org\/download\/AQPRadio350\/MixRelax67_electronic.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Relax 67 &#8211; Electronic\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-7387","post","type-post","status-publish","format-standard","hentry","category-musica-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/7387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=7387"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/7387\/revisions"}],"predecessor-version":[{"id":87755,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/7387\/revisions\/87755"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=7387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=7387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=7387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}