{"id":7845,"date":"2025-03-05T19:19:08","date_gmt":"2025-03-05T19:19:08","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=7845"},"modified":"2026-06-29T12:52:25","modified_gmt":"2026-06-29T17:52:25","slug":"sonora-carruseles","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/7845","title":{"rendered":"Sonora Carruseles"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/Exr5M4PVUZw\/maxresdefault.jpg\" alt=\"\" width=\"98%\" align=\"center\" \/><\/p>\n<p> \u00abSonora Carruseles\u00bb <\/p>\n<p><strong>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-7845-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio364\/Mix_SonoraCarruseles.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio364\/Mix_SonoraCarruseles.mp3\">http:\/\/archive.org\/download\/AQPRadio364\/Mix_SonoraCarruseles.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSonora Carruseles\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-7845","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/7845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=7845"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/7845\/revisions"}],"predecessor-version":[{"id":85142,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/7845\/revisions\/85142"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=7845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=7845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=7845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}