{"id":8248,"date":"2025-03-30T13:48:57","date_gmt":"2025-03-30T13:48:57","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=8248"},"modified":"2026-06-29T12:47:25","modified_gmt":"2026-06-29T17:47:25","slug":"mix-todo-mezclado-18","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/8248","title":{"rendered":"Mix Todo Mezclado &#8211; 18"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/estudiovila13.com\/wp-content\/uploads\/3-discoteca-hi-ibiza.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p> \u00abMix Todo Mezclado &#8211; 18\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-8248-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio378\/Mix_Todomezclado18.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio378\/Mix_Todomezclado18.mp3\">http:\/\/archive.org\/download\/AQPRadio378\/Mix_Todomezclado18.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Todo Mezclado &#8211; 18\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-8248","post","type-post","status-publish","format-standard","hentry","category-todo-mezclado"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/8248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=8248"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/8248\/revisions"}],"predecessor-version":[{"id":84818,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/8248\/revisions\/84818"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=8248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=8248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=8248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}