{"id":8320,"date":"2025-04-02T23:16:43","date_gmt":"2025-04-02T23:16:43","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=8320"},"modified":"2026-06-29T12:46:47","modified_gmt":"2026-06-29T17:46:47","slug":"henry-salomon-orchestra-temas-de-amor","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/8320","title":{"rendered":"Henry Salomon Orchestra &#8211; Temas de Amor"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/cdn-images.dzcdn.net\/images\/cover\/aa27be82c048de79b393ab840f7acee2\/1900x1900-000000-80-0-0.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p> \u00abHenry Salomon Orchestra &#8211; Temas de Amor\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-8320-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio380\/Mix_HenrySalomonOrchestra_TemasdeAmor.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio380\/Mix_HenrySalomonOrchestra_TemasdeAmor.mp3\">http:\/\/archive.org\/download\/AQPRadio380\/Mix_HenrySalomonOrchestra_TemasdeAmor.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abHenry Salomon Orchestra &#8211; Temas de Amor\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-8320","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/8320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=8320"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/8320\/revisions"}],"predecessor-version":[{"id":84774,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/8320\/revisions\/84774"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=8320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=8320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=8320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}