{"id":8447,"date":"2025-04-11T17:56:35","date_gmt":"2025-04-11T17:56:35","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=8447"},"modified":"2026-08-12T20:40:06","modified_gmt":"2026-08-13T01:40:06","slug":"lucia-de-la-cruz","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/8447","title":{"rendered":"Luc\u00eda de la Cruz"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/3.bp.blogspot.com\/_nhaBaPqte2Q\/TUYrDLTe7tI\/AAAAAAAACD8\/mkf5H3FxXDw\/s320\/LUCIA_DE_LA_CRUZ.JPG\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abLuc\u00eda de la Cruz\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-8447-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio385\/Mix_LuciadelaCruz.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio385\/Mix_LuciadelaCruz.mp3\">http:\/\/archive.org\/download\/AQPRadio385\/Mix_LuciadelaCruz.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLuc\u00eda de la Cruz\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-8447","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/8447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=8447"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/8447\/revisions"}],"predecessor-version":[{"id":97089,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/8447\/revisions\/97089"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=8447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=8447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=8447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}