{"id":9037,"date":"2025-05-20T06:08:33","date_gmt":"2025-05-20T06:08:33","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=9037"},"modified":"2026-06-29T11:07:45","modified_gmt":"2026-06-29T16:07:45","slug":"elton-john-canciones-de-amor","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/actual\/archivos\/9037","title":{"rendered":"Elton John  &#8211; Canciones de Amor"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/6\/61\/EltonDocBFILFF101024_%284_of_17%29_%28cropped%29.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abElton John  &#8211; Canciones de Amor\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-9037-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/archive.org\/download\/AQPRadio406\/Mix_EltonJohn.mp3?_=1\" \/><a href=\"http:\/\/archive.org\/download\/AQPRadio406\/Mix_EltonJohn.mp3\">http:\/\/archive.org\/download\/AQPRadio406\/Mix_EltonJohn.mp3<\/a><\/audio>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abElton John &#8211; Canciones de Amor\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[83],"tags":[],"class_list":["post-9037","post","type-post","status-publish","format-standard","hentry","category-baul-de-los-recuerdos"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/9037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/comments?post=9037"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/9037\/revisions"}],"predecessor-version":[{"id":84172,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/posts\/9037\/revisions\/84172"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/media?parent=9037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/categories?post=9037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/actual\/wp-json\/wp\/v2\/tags?post=9037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}