{"id":13435,"date":"2015-03-08T13:06:29","date_gmt":"2015-03-08T18:06:29","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=13435"},"modified":"2026-07-05T02:44:58","modified_gmt":"2026-07-05T02:44:58","slug":"myron-floren-y-su-acordeon-disco-polka","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/13435\/myron-floren-y-su-acordeon-disco-polka\/","title":{"rendered":"Myron Floren y su Acorde\u00f3n &#8211; Disco Polka"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Myron Floren y su Acorde\u00f3n &#8211; Disco Polka\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/i.pinimg.com\/originals\/3a\/2b\/5b\/3a2b5baccaae9800b8319a5ce4abeb30.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abMyron Floren y su Acorde\u00f3n &#8211; Disco Polka\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMyron Floren y su Acorde\u00f3n &#8211; Disco Polka\u00bb Active el Player de Sonido para que goce con las dulces melodias [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2,3],"tags":[117,4,5,6,7,17,9,14,13,16],"class_list":["post-13435","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","category-orchestra","tag-acordeon","tag-instrumental","tag-instrumentales","tag-music-orchestrated","tag-musica-en-linea","tag-musica-instrumentada","tag-musica-orquestada","tag-musique-orchestree","tag-muzica-orchestrate","tag-muziek-orchestrated"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/13435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=13435"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/13435\/revisions"}],"predecessor-version":[{"id":39233,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/13435\/revisions\/39233"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=13435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=13435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=13435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}