{"id":13769,"date":"2015-05-17T12:03:05","date_gmt":"2015-05-17T17:03:05","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=13769"},"modified":"2026-07-05T02:44:36","modified_gmt":"2026-07-05T02:44:36","slug":"mix-relax-126-panpipes","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/13769\/mix-relax-126-panpipes\/","title":{"rendered":"Mix Relax &#8211; 126 &#8211; Panpipes"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix Relax &#8211; 126 &#8211; Panpipes\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/upload.wikimedia.org\/wikipedia\/commons\/0\/0e\/Pan_flute_played_1.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abMix Relax &#8211; 126 &#8211; Panpipes\u00bb  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abMix [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[19],"tags":[323,349,20],"class_list":["post-13769","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-pan-flute","tag-pan-pipes","tag-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/13769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=13769"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/13769\/revisions"}],"predecessor-version":[{"id":39182,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/13769\/revisions\/39182"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=13769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=13769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=13769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}