{"id":15416,"date":"2015-09-24T21:53:25","date_gmt":"2015-09-25T02:53:25","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=15416"},"modified":"2026-07-05T02:44:10","modified_gmt":"2026-07-05T02:44:10","slug":"mix-musica-orquestada-219","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/15416\/mix-musica-orquestada-219\/","title":{"rendered":"Mix M\u00fasica Orquestada &#8211; 219"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix M\u00fasica Orquestada &#8211; 219\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/i.ytimg.com\/vi\/X-wL72KKP1w\/maxresdefault.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abMix M\u00fasica Orquestada &#8211; 219\u00bb <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abMix [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[7,8,9,11,12,14,13,16,15],"class_list":["post-15416","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","tag-musica-en-linea","tag-musica-orchestrata","tag-musica-orquestada","tag-musik-iscenesat","tag-musik-orchestriert","tag-musique-orchestree","tag-muzica-orchestrate","tag-muziek-orchestrated","tag-orquestadas"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/15416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=15416"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/15416\/revisions"}],"predecessor-version":[{"id":39118,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/15416\/revisions\/39118"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=15416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=15416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=15416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}