{"id":15418,"date":"2015-09-24T21:55:53","date_gmt":"2015-09-25T02:55:53","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=15418"},"modified":"2026-07-05T02:44:09","modified_gmt":"2026-07-05T02:44:09","slug":"mix-todomezclado-63-lounge-70s","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/15418\/mix-todomezclado-63-lounge-70s\/","title":{"rendered":"Mix Todomezclado &#8211; 63 &#8211; Lounge 70s"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix Todomezclado &#8211; 63 &#8211; Lounge 70s\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/aqpradios.com\/relaxmusical\/imagenaqp\/escuchandoaqpradio27.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abMix Todomezclado &#8211; 63 &#8211; Lounge 70s\u00bb <\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abMix [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[19],"tags":[35,4,5,378,7],"class_list":["post-15418","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-70s","tag-instrumental","tag-instrumentales","tag-lounge","tag-musica-en-linea"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/15418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=15418"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/15418\/revisions"}],"predecessor-version":[{"id":39117,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/15418\/revisions\/39117"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=15418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=15418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=15418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}