{"id":15533,"date":"2015-10-15T11:49:16","date_gmt":"2015-10-15T16:49:16","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=15533"},"modified":"2026-08-31T23:49:41","modified_gmt":"2026-08-31T23:49:41","slug":"mix-relax-128-clasicos","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/15533\/mix-relax-128-clasicos\/","title":{"rendered":"Mix Relax 128 &#8211; Cl\u00e1sicos"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix Relax 128 &#8211; Cl\u00e1sicos\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/i.ytimg.com\/vi\/OvUywK-v-4Q\/maxresdefault.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abMix Relax 128 &#8211; Cl\u00e1sicos\u00bb <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abMix [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[19],"tags":[4,5,7,18],"class_list":["post-15533","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-instrumental","tag-instrumentales","tag-musica-en-linea","tag-musica-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/15533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=15533"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/15533\/revisions"}],"predecessor-version":[{"id":41770,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/15533\/revisions\/41770"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=15533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=15533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=15533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}