{"id":1554,"date":"2018-10-20T09:25:25","date_gmt":"2018-10-20T09:25:25","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=1554"},"modified":"2026-08-31T23:14:53","modified_gmt":"2026-08-31T23:14:53","slug":"mix-musica-orquestada-127","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/1554\/mix-musica-orquestada-127\/","title":{"rendered":"Mix M\u00fasica Orquestada 127"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix M\u00fasica Orquestada 127\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/2.bp.blogspot.com\/-Ux2Jbn4JFDg\/TgNiw9Xgw0I\/AAAAAAAABWQ\/AWHYqGfDYQs\/s1600\/2uzvhhybsfp.gif\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abMix M\u00fasica Orquestada 127\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix M\u00fasica Orquestada 127\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2,3],"tags":[6,7,8,9,10,11,12,14,13,16],"class_list":["post-1554","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","category-orchestra","tag-music-orchestrated","tag-musica-en-linea","tag-musica-orchestrata","tag-musica-orquestada","tag-musiikki-orkestroinut","tag-musik-iscenesat","tag-musik-orchestriert","tag-musique-orchestree","tag-muzica-orchestrate","tag-muziek-orchestrated"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/1554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=1554"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/1554\/revisions"}],"predecessor-version":[{"id":41025,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/1554\/revisions\/41025"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=1554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=1554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=1554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}