{"id":17039,"date":"2016-05-24T18:48:39","date_gmt":"2016-05-24T23:48:39","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=17039"},"modified":"2026-08-31T23:48:24","modified_gmt":"2026-08-31T23:48:24","slug":"network-music-ensemble","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/17039\/network-music-ensemble\/","title":{"rendered":"Network Music Ensemble"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/1.bp.blogspot.com\/-BQAclNa6d2w\/UJ6-JeucxlI\/AAAAAAAAAAU\/E_HFGmcs5Xo\/s1600\/imagen+para+blog.jpg\" alt=\"Network Music Ensemble\" width=\"98%\" align=\"middle\" \/><\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p>\u00abNetwork Music Ensemble\u00bb <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio. \u00abNetwork [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[19],"tags":[4,5,7,20],"class_list":["post-17039","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-instrumental","tag-instrumentales","tag-musica-en-linea","tag-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/17039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=17039"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/17039\/revisions"}],"predecessor-version":[{"id":41620,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/17039\/revisions\/41620"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=17039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=17039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=17039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}