{"id":18524,"date":"2017-04-15T00:30:01","date_gmt":"2017-04-15T05:30:01","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=18524"},"modified":"2026-07-05T02:41:48","modified_gmt":"2026-07-05T02:41:48","slug":"ticiano-maia-2","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/18524\/ticiano-maia-2\/","title":{"rendered":"Ticiano Maia &#8211; 2"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Ticiano Maia &#8211; 2\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/4.bp.blogspot.com\/-qI0hhVtP_Ks\/VVaIWHZiRlI\/AAAAAAAACp8\/7eXdH5et-O8\/s1600\/TICIANO%2BMAIA-VOL.5%2BCAPA001.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abTiciano Maia &#8211; 2\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abTiciano Maia &#8211; 2\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[4,5,7,30],"class_list":["post-18524","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","tag-instrumental","tag-instrumentales","tag-musica-en-linea","tag-piano"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/18524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=18524"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/18524\/revisions"}],"predecessor-version":[{"id":38800,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/18524\/revisions\/38800"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=18524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=18524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=18524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}