{"id":27397,"date":"2019-08-25T13:05:57","date_gmt":"2019-08-25T18:05:57","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=27397"},"modified":"2026-07-05T02:34:56","modified_gmt":"2026-07-05T02:34:56","slug":"mix-ecos-del-ayer-17","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/27397\/mix-ecos-del-ayer-17\/","title":{"rendered":"Mix Ecos del Ayer &#8211; 17"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix Ecos del Ayer &#8211; 17\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/aqpradios.com\/relaxmusical\/imagenaqp\/escuchandoaqpradio38.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abMix Ecos del Ayer &#8211; 17\u00bb<\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Ecos del Ayer &#8211; 17\u00bb Active el Player de Sonido para que goce con las dulces melodias que les [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[19],"tags":[24,25,7,18,20],"class_list":["post-27397","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-canciones-del-ayer","tag-canciones-del-recuerdo","tag-musica-en-linea","tag-musica-relax","tag-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/27397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=27397"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/27397\/revisions"}],"predecessor-version":[{"id":37851,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/27397\/revisions\/37851"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=27397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=27397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=27397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}