{"id":27550,"date":"2019-11-16T14:06:28","date_gmt":"2019-11-16T19:06:28","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=27550"},"modified":"2026-07-05T02:34:04","modified_gmt":"2026-07-05T02:34:04","slug":"mix-relax-227-romance","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/27550\/mix-relax-227-romance\/","title":{"rendered":"Mix Relax 229 &#8211; Romance"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix Relax 229 &#8211; Romance\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/southhope.files.wordpress.com\/2013\/05\/villa-paraiso-1.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abMix Relax 229 &#8211; Romance\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Relax 229 &#8211; Romance\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[19],"tags":[4,5,7,18,20,402],"class_list":["post-27550","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-instrumental","tag-instrumentales","tag-musica-en-linea","tag-musica-relax","tag-relax","tag-romanticas"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/27550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=27550"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/27550\/revisions"}],"predecessor-version":[{"id":37749,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/27550\/revisions\/37749"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=27550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=27550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=27550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}