{"id":29471,"date":"2020-11-16T16:52:01","date_gmt":"2020-11-16T21:52:01","guid":{"rendered":"http:\/\/aqpradios.com\/musicaenlinea\/?p=29471"},"modified":"2026-07-05T02:30:43","modified_gmt":"2026-07-05T02:30:43","slug":"ernesto-cortazar-y-su-piano-2","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/29471\/ernesto-cortazar-y-su-piano-2\/","title":{"rendered":"Ernesto Cortazar y su Piano &#8211; 2"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Ernesto Cortazar y su Piano &#8211; 2\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/i.ytimg.com\/vi\/j8h_M6yy0j4\/maxresdefault.jpg\" align=\"center\" width=\"98%\"><\/p>\n<p>\u00abErnesto Cortazar y su Piano &#8211; 2\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abErnesto Cortazar y su Piano &#8211; 2\u00bb Active el Player de Sonido para que goce con las dulces melodias que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[19],"tags":[7,18,30,20],"class_list":["post-29471","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-musica-en-linea","tag-musica-relax","tag-piano","tag-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/29471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=29471"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/29471\/revisions"}],"predecessor-version":[{"id":38063,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/29471\/revisions\/38063"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=29471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=29471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=29471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}