{"id":2960,"date":"2019-05-01T04:36:04","date_gmt":"2019-05-01T04:36:04","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=2960"},"modified":"2026-07-05T02:36:07","modified_gmt":"2026-07-05T02:36:07","slug":"mix-manuel-alejandro-y-orquesta","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/2960\/mix-manuel-alejandro-y-orquesta\/","title":{"rendered":"Mix Manuel Alejandro y Orquesta"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix Manuel Alejandro y Orquesta\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/www.diariodecadiz.es\/2011\/11\/09\/ocio\/compositor-jerezano-Manuel-Alejandro_531857027_22045017_1545x1024.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abMix Manuel Alejandro y Orquesta\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Manuel Alejandro y Orquesta\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[94,6,7,8,9,12,14,13,16],"class_list":["post-2960","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","tag-manuel-alejandro","tag-music-orchestrated","tag-musica-en-linea","tag-musica-orchestrata","tag-musica-orquestada","tag-musik-orchestriert","tag-musique-orchestree","tag-muzica-orchestrate","tag-muziek-orchestrated"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/2960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=2960"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/2960\/revisions"}],"predecessor-version":[{"id":38000,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/2960\/revisions\/38000"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=2960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=2960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=2960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}