{"id":2981,"date":"2019-05-06T05:28:44","date_gmt":"2019-05-06T05:28:44","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=2981"},"modified":"2026-08-31T23:12:39","modified_gmt":"2026-08-31T23:12:39","slug":"mix-los-violines-magicos-de-villafontana","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/2981\/mix-los-violines-magicos-de-villafontana\/","title":{"rendered":"Los Violines Magicos de Villafontana"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Los Violines Magicos de Villafontana\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/3.bp.blogspot.com\/_JXOlPZzOQyk\/SDn4FviB3dI\/AAAAAAAACHA\/-grquf3e0-0\/s400\/Imagen2.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abMix Violines Magicos de Villafontana\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Violines Magicos de Villafontana\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[19],"tags":[7,9,18,37],"class_list":["post-2981","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-musica-en-linea","tag-musica-orquestada","tag-musica-relax","tag-violin"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/2981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=2981"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/2981\/revisions"}],"predecessor-version":[{"id":40779,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/2981\/revisions\/40779"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=2981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=2981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=2981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}