{"id":498,"date":"2018-11-12T19:45:44","date_gmt":"2018-11-12T19:45:44","guid":{"rendered":"http:\/\/dulcesmelodias.xtreemhost.com\/?p=498"},"modified":"2026-07-05T02:38:01","modified_gmt":"2026-07-05T02:38:01","slug":"mix-musica-relax-8","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/498\/mix-musica-relax-8\/","title":{"rendered":"Mix M\u00fasica Relax 8"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix M\u00fasica Relax 8\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/4.bp.blogspot.com\/-332x1Gedezc\/WqmEeAOcmwI\/AAAAAAAB0yM\/Pth_pG5DpCYBs5-ZhYLZHgoM2kNysMN5wCK4BGAYYCw\/s1600\/imagenes-paisajes-hermosos-fondos-de-pantalla-playa.jpg\" width=\"98%\" align=\"center\"> <\/p>\n<p>\u00abMix M\u00fasica Relax 8\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix M\u00fasica Relax 8\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[19],"tags":[4,5,7,18,20],"class_list":["post-498","post","type-post","status-publish","format-standard","hentry","category-musica-relax","tag-instrumental","tag-instrumentales","tag-musica-en-linea","tag-musica-relax","tag-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=498"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/498\/revisions"}],"predecessor-version":[{"id":38345,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/498\/revisions\/38345"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}