{"id":7031,"date":"2020-09-13T20:30:29","date_gmt":"2020-09-13T20:30:29","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=7031"},"modified":"2026-07-05T02:31:20","modified_gmt":"2026-07-05T02:31:20","slug":"sucedio-en-el-ayer-1-instrumentales","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/7031\/sucedio-en-el-ayer-1-instrumentales\/","title":{"rendered":"Sucedi\u00f3 en el Ayer &#8211; 1 &#8211; Instrumentales"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/diariocorreo.pe\/resizer\/CaTF5H0MmIu8vXRtDtjgnewHoXA=\/1200x900\/smart\/filters:format(jpeg):quality(75)\/arc-anglerfish-arc2-prod-elcomercio.s3.amazonaws.com\/public\/7Q3AKAPE6BEBZK22SNOTROSL2E.jpg\" alt=\"Sucedi\u00f3 en el Ayer &#8211; 1 &#8211; Instrumentales\" width=\"98%\" align=\"center\" \/><\/p>\n<p>\u00abSucedi\u00f3 en el Ayer &#8211; 1 &#8211; Instrumentales\u00bb <\/p>\n<p><strong>Active el Player de Sonido para que goce con las dulces melod\u00edas que les brindamos. Fina cortes\u00eda de AQPRadio.<\/strong><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSucedi\u00f3 en el Ayer &#8211; 1 &#8211; Instrumentales\u00bb Active el Player de Sonido para que goce con las dulces melod\u00edas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2,36],"tags":[6,42,7,8,9,10,11,12,14,13,16],"class_list":["post-7031","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","category-sucedio-en-los","tag-music-orchestrated","tag-musica-disco-soul","tag-musica-en-linea","tag-musica-orchestrata","tag-musica-orquestada","tag-musiikki-orkestroinut","tag-musik-iscenesat","tag-musik-orchestriert","tag-musique-orchestree","tag-muzica-orchestrate","tag-muziek-orchestrated"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/7031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=7031"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/7031\/revisions"}],"predecessor-version":[{"id":38135,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/7031\/revisions\/38135"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=7031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=7031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=7031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}