{"id":8142,"date":"2013-06-13T18:15:50","date_gmt":"2013-06-13T23:15:50","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=8142"},"modified":"2026-07-05T02:49:16","modified_gmt":"2026-07-05T02:49:16","slug":"mix-andre-brasseur-2","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/8142\/mix-andre-brasseur-2\/","title":{"rendered":"Mix Andr\u00e9 Brasseur &#8211; 2"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix Andr\u00e9 Brasseur &#8211; 2\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/www.memoire60-70.be\/Images\/Chronique_1966_1972\/Ciney_Andre_Brasseur_1966_0.jpg\" width=\"98%\" align=\"center\"><br \/>\n \u00abMix Andr\u00e9 Brasseur &#8211; 2\u00bb  Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Andr\u00e9 Brasseur &#8211; 2\u00bb Active el Player de Sonido para que goce con las dulces melodias que les brindamos. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[223,6,7,8,9,10,12,14,13,16,15],"class_list":["post-8142","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","tag-andre-brasseur","tag-music-orchestrated","tag-musica-en-linea","tag-musica-orchestrata","tag-musica-orquestada","tag-musiikki-orkestroinut","tag-musik-orchestriert","tag-musique-orchestree","tag-muzica-orchestrate","tag-muziek-orchestrated","tag-orquestadas"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=8142"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8142\/revisions"}],"predecessor-version":[{"id":39760,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8142\/revisions\/39760"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=8142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=8142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=8142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}