{"id":8274,"date":"2013-06-29T19:25:16","date_gmt":"2013-06-30T00:25:16","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=8274"},"modified":"2026-07-05T02:49:03","modified_gmt":"2026-07-05T02:49:03","slug":"alberto-semprini-the-golden-moments","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/8274\/alberto-semprini-the-golden-moments\/","title":{"rendered":"Alberto Semprini &#8211; The Golden Moments"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Alberto Semprini &#8211; The Golden Moments\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/c8.alamy.com\/comp\/F58RNE\/alberto-semprini-1908-1990-english-pianist-F58RNE.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p>\u00abAlberto Semprini &#8211; The Golden Moments\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abAlberto Semprini &#8211; The Golden Moments\u00bb Active el Player de Sonido para que goce con las dulces melodias que les [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[210,6,7,8,9,10,14,13,16,15],"class_list":["post-8274","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","tag-alberto-semprini","tag-music-orchestrated","tag-musica-en-linea","tag-musica-orchestrata","tag-musica-orquestada","tag-musiikki-orkestroinut","tag-musique-orchestree","tag-muzica-orchestrate","tag-muziek-orchestrated","tag-orquestadas"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=8274"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8274\/revisions"}],"predecessor-version":[{"id":39737,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8274\/revisions\/39737"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=8274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=8274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=8274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}