{"id":8343,"date":"2013-07-12T21:20:28","date_gmt":"2013-07-13T02:20:28","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=8343"},"modified":"2026-07-05T02:48:56","modified_gmt":"2026-07-05T02:48:56","slug":"glen-gray-and-the-casa-loma-orchestra","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/8343\/glen-gray-and-the-casa-loma-orchestra\/","title":{"rendered":"Glen Gray and the Casa Loma Orchestra"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Glen Gray and the Casa Loma Orchestra\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/2.bp.blogspot.com\/_mxsqCaLHGLk\/TS84beQ7_gI\/AAAAAAAAAiY\/aYNJIR7u9iU\/s1600\/GlenGrayCasaLomaOrchestra.jpg\" width=\"98%\" align=\"center\"><br \/>\n \u00abGlen Gray and the Casa Loma Orchestra\u00bb  <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abGlen Gray and the Casa Loma Orchestra\u00bb Active el Player de Sonido para que goce con las dulces melodias que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2],"tags":[247,6,7,8,9,11,14,13,16,15],"class_list":["post-8343","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","tag-casa-loma","tag-music-orchestrated","tag-musica-en-linea","tag-musica-orchestrata","tag-musica-orquestada","tag-musik-iscenesat","tag-musique-orchestree","tag-muzica-orchestrate","tag-muziek-orchestrated","tag-orquestadas"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=8343"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8343\/revisions"}],"predecessor-version":[{"id":39720,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8343\/revisions\/39720"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=8343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=8343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=8343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}