{"id":8606,"date":"2013-08-13T22:18:09","date_gmt":"2013-08-14T03:18:09","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=8606"},"modified":"2026-07-05T02:48:34","modified_gmt":"2026-07-05T02:48:34","slug":"edward-simoni-daniela-de-santos","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/8606\/edward-simoni-daniela-de-santos\/","title":{"rendered":"Edward Simoni &#038; Daniela de Santos"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Edward Simoni &#038; Daniela de Santos\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"http:\/\/3.bp.blogspot.com\/-TATKqWhY1xc\/Ufl3B-d6o7I\/AAAAAAAAMVs\/xl-pd1Hrovs\/s400\/Pan-Magie+-+Zauber+der+Panfl%C3%B6ten+%281998%29.jpg\" width=\"98%\" align=\"center\"><br \/>\n \u00abEdward Simoni &#038; Daniela de Santos\u00bb  <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abEdward Simoni &#038; Daniela de Santos\u00bb Active el Player de Sonido para que goce con las dulces melodias que les [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2,19,3,23],"tags":[6,7,8,9,18,10,11,12,14,13,16,15],"class_list":["post-8606","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","category-musica-relax","category-orchestra","category-tributo-a","tag-music-orchestrated","tag-musica-en-linea","tag-musica-orchestrata","tag-musica-orquestada","tag-musica-relax","tag-musiikki-orkestroinut","tag-musik-iscenesat","tag-musik-orchestriert","tag-musique-orchestree","tag-muzica-orchestrate","tag-muziek-orchestrated","tag-orquestadas"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=8606"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8606\/revisions"}],"predecessor-version":[{"id":39679,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8606\/revisions\/39679"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=8606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=8606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=8606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}