{"id":8901,"date":"2013-09-19T13:36:49","date_gmt":"2013-09-19T18:36:49","guid":{"rendered":"http:\/\/aqpradio.info\/musicaenlinea\/?p=8901"},"modified":"2026-07-05T02:48:10","modified_gmt":"2026-07-05T02:48:10","slug":"mix-relax-94-clifford-white","status":"publish","type":"post","link":"https:\/\/aqpradios.com\/relaxmusical\/archivos\/8901\/mix-relax-94-clifford-white\/","title":{"rendered":"Mix Relax 94 &#8211; Clifford White"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"Mix Relax 94 &#8211; Clifford White\" loading=\"lazy\" loading=\"lazy\" loading=\"lazy\" src=\"https:\/\/aqpradios.com\/relaxmusical\/imagenaqp\/elegante8.jpg\" width=\"98%\" align=\"center\"><\/p>\n<p> \u00abMix Relax 94 &#8211; Clifford White\u00bb <\/p>\n<p>Active el Player de Sonido para que goce con las dulces melodias que les brindamos. Fina cortes\u00eda de AQPRadio.<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abMix Relax 94 &#8211; Clifford White\u00bb Active el Player de Sonido para que goce con las dulces melodias que les [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[2,19,3],"tags":[4,5,7,8,12,13,15,20],"class_list":["post-8901","post","type-post","status-publish","format-standard","hentry","category-musica-orquestada","category-musica-relax","category-orchestra","tag-instrumental","tag-instrumentales","tag-musica-en-linea","tag-musica-orchestrata","tag-musik-orchestriert","tag-muzica-orchestrate","tag-orquestadas","tag-relax"],"_links":{"self":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/comments?post=8901"}],"version-history":[{"count":1,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8901\/revisions"}],"predecessor-version":[{"id":39625,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/posts\/8901\/revisions\/39625"}],"wp:attachment":[{"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/media?parent=8901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/categories?post=8901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aqpradios.com\/relaxmusical\/wp-json\/wp\/v2\/tags?post=8901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}